{"id":6827,"date":"2022-09-21T18:45:46","date_gmt":"2022-09-21T18:45:46","guid":{"rendered":"https:\/\/rhinoequipment.us\/?page_id=6827"},"modified":"2024-12-30T21:20:52","modified_gmt":"2024-12-30T21:20:52","slug":"rh3255ex-hydraulic-hammer","status":"publish","type":"page","link":"https:\/\/rhinoequipment.us\/pt\/rh3255ex-hydraulic-hammer\/","title":{"rendered":"RH3255EX"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6827\" class=\"elementor elementor-6827\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc9161d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc9161d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c0e72a5\" data-id=\"c0e72a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f62b21e elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"f62b21e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc3NSIsInRvZ2dsZSI6ZmFsc2V9\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Fa\u00e7a uma pergunta\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-question-circle\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6Ijc3NSIsInRvZ2dsZSI6ZmFsc2V9\" >\n\t\t\t\t\t\t\tFa\u00e7a uma pergunta\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a684c2\" data-id=\"2a684c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fc2669 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"2fc2669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/rhinoequipment.us\/pt\/rh3255exquote\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Solicite um or\u00e7amento\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-pencil\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/rhinoequipment.us\/pt\/rh3255exquote\/\" >\n\t\t\t\t\t\t\tSolicite um or\u00e7amento\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cd77c64\" data-id=\"cd77c64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60718ac elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"60718ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2024\/07\/Hammers-2024.pdf\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Download do folheto\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-book-open\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2024\/07\/Hammers-2024.pdf\" target=\"_blank\" >\n\t\t\t\t\t\t\tDownload do folheto\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6f3d97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6f3d97\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1de02fe\" data-id=\"1de02fe\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9818d78 elementor-widget elementor-widget-heading\" data-id=\"9818d78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">MARTELO HIDR\u00c1ULICO RH3255EX<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1181cbc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1181cbc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46acb5b\" data-id=\"46acb5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2984ca4 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"2984ca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-5155cfb swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Javier C\u00e1rdenas, President and CEO Rhino Equipment\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4940a33 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Javier C\u00e1rdenas, President and CEO Rhino Equipment\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d35009f\" data-id=\"d35009f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e58ab69 elementor-widget elementor-widget-heading\" data-id=\"e58ab69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Efficiency and Profitability<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d07da elementor-widget elementor-widget-heading\" data-id=\"15d07da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MAXIMIZE O TEMPO DE ATIVIDADE E AUMENTE A EFICI\u00caNCIA E A RENTABILIDADE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad63aa elementor-widget elementor-widget-text-editor\" data-id=\"5ad63aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O RH3255 com uma ampla gama de compatibilidade de transportadores \u00e9 um rompedor para todos os trabalhos, seja demoli\u00e7\u00e3o comercial, constru\u00e7\u00e3o de estradas, trabalho em pedreiras ou quebra de produ\u00e7\u00e3o. Um design superior permite uma gama mais ampla de press\u00f5es e fluxos. Al\u00e9m disso, o peso leve da ferramenta contribui para uma faixa de suporte mais ampla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8442f30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8442f30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-02d4ac0\" data-id=\"02d4ac0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8abf9ee elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8abf9ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rhinoequipment.us\/comparison\/3550EXcomparison.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Baixe o gr\u00e1fico de compara\u00e7\u00e3o<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-08d5db5\" data-id=\"08d5db5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d88f1a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5d88f1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rhinoequipment.us\/pt\/rh3255exquote\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicite um or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ca43bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ca43bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6887a91\" data-id=\"6887a91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84aace0 elementor-widget elementor-widget-spacer\" data-id=\"84aace0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-708b050 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"708b050\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-19b2032\" data-id=\"19b2032\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f1554f elementor-widget elementor-widget-image\" data-id=\"7f1554f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"288\" src=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf3.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6777\" alt=\"RH1826EX HYDRAULIC HAMMER\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522fbc2 elementor-widget elementor-widget-heading\" data-id=\"522fbc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">KIT DE ACESS\u00d3RIOS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b30c87 elementor-widget elementor-widget-text-editor\" data-id=\"3b30c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kit de acess\u00f3rios completo para opera\u00e7\u00e3o adequada. Um martelo hidr\u00e1ulico converte energia hidr\u00e1ulica em energia cin\u00e9tica. A energia cin\u00e9tica \u00e9 fornecida pelo pist\u00e3o do martelo \u00e0 ferramenta como uma for\u00e7a de impacto. Escolha e use a ferramenta mais adequada para o trabalho.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-01457cd\" data-id=\"01457cd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3b9318 elementor-widget elementor-widget-image\" data-id=\"c3b9318\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"288\" src=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6775\" alt=\"RH1826EX HYDRAULIC HAMMER\" srcset=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf1.jpg 400w, https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf1-300x216.jpg 300w, https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf1-18x12.jpg 18w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99f7f31 elementor-widget elementor-widget-heading\" data-id=\"99f7f31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">COMPONENTES DE QUALIDADE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8bd841 elementor-widget elementor-widget-text-editor\" data-id=\"f8bd841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Menos manuten\u00e7\u00e3o \u00e9 necess\u00e1ria durante a vida \u00fatil do rompedor porque a ferramenta foi fabricada com componentes de alta qualidade para extrema durabilidade nas aplica\u00e7\u00f5es mais severas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43aaeab\" data-id=\"43aaeab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57067fb elementor-widget elementor-widget-image\" data-id=\"57067fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"400\" height=\"288\" src=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf2.jpg\" class=\"attachment-medium_large size-medium_large wp-image-6776\" alt=\"hydraulic breakers\" srcset=\"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf2.jpg 400w, https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf2-300x216.jpg 300w, https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf2-18x12.jpg 18w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d5b072 elementor-widget elementor-widget-heading\" data-id=\"2d5b072\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAIXA DE FERRAMENTAS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd7fff elementor-widget elementor-widget-text-editor\" data-id=\"7fd7fff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A caixa de ferramentas completa dos martelos Rhino permite que voc\u00ea mantenha seu equipamento em \u00f3timas condi\u00e7\u00f5es, servi\u00e7o e instala\u00e7\u00e3o adequada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aab1845 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aab1845\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eff84b9\" data-id=\"eff84b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6191f4d elementor-widget elementor-widget-spacer\" data-id=\"6191f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d596c59 elementor-widget elementor-widget-accordion\" data-id=\"d596c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2231\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2231\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PAR\u00c2METROS PRINCIPAIS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2231\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2231\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"6725\" class=\"elementor elementor-6725\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-589cfad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"589cfad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c32291a\" data-id=\"c32291a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-406115e elementor-widget elementor-widget-elementskit-tablepress\" data-id=\"406115e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-tablepress.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elemenetskit-tablepress ekit-wid-con\" id=\"ekit_tablepress_406115e\">\n<table id=\"tablepress-594\" class=\"tablepress tablepress-id-594\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Toneladas de Classe de Equipamento<\/td><td class=\"column-2\">32 &#8211; 55<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Peso Operacional Kgs (lbs)<\/td><td class=\"column-2\">3,020 (6,658)<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Peso do corpo principal Kgs (lbs)<\/td><td class=\"column-2\">1,400 (3,087)<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Altura (incl.ferramenta) mm (polegadas)<\/td><td class=\"column-2\">2,740 (108)<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Faixa de vaz\u00e3o l\/min (gal\/min)<\/td><td class=\"column-2\">190-250 (50-65)<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Barra de press\u00e3o operacional (psi)<\/td><td class=\"column-2\">160-180 (2,321-2,611)<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Faixa de impacto bmp<\/td><td class=\"column-2\">250-400<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Haste \/ Cinzel mm (polegada)<\/td><td class=\"column-2\">160 (6.30)<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Di\u00e2metro da mangueira (polegadas)<\/td><td class=\"column-2\">1 1\/4<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Classe de Energia de Impacto Kg\/m (ft x lb)<\/td><td class=\"column-2\">1,020 (7,376)<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Barra de press\u00e3o do g\u00e1s da cabe\u00e7a traseira (psi)<\/td><td class=\"column-2\">9-131<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-594 from cache --><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341adab elementor-widget elementor-widget-spacer\" data-id=\"341adab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d72378f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d72378f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14d7ca3\" data-id=\"14d7ca3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-373bdfe elementor-widget elementor-widget-text-editor\" data-id=\"373bdfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span id=\"contenido-oculto\" style=\"font-size: 16px;\"> RH3255EX HYDRAULIC HAMMER vulputate. Aliquam mollis sed dui et viverra. RH3255EX HYDRAULIC HAMMER Aliquam in auctor ante, RH3255EX HYDRAULIC HAMMER sed congue edrat. imperdiet. RH3255EX HYDRAULIC HAMMER Curabitur tincidunt sollicitudin ligula. RH3255EX HYDRAULIC HAMMER Morbi quis nibh nec ipsum laoreet conseqcuat non nec nulla. RH3255EX HYDRAULIC HAMMER Aliquam in auctor ante, RH3255EX HYDRAULIC HAMMER sed congue erat. imperdiet. RH3255EX HYDRAULIC HAMMER Curabitur tincidunt Phasellus quis molestie mauris. RH3255EX HYDRAULIC HAMMER Mauris auctor venenatis ante, RH3255EX HYDRAULIC HAMMER eu rhoncus eros pulvinar at. Quisque rhoncus non arcu ut vestibulum. Donec luctus varius nibh, sed commodo magna porttitor sit amet. Sed risus nunc, RH3255EX HYDRAULIC HAMMER iaculis eget rutrum maximus Proin a sapien est. Sed porta est nec porttitor dignissim. Maecenas nulla libero, bibendum ac enim vel, luctus pharetra neque. liquam erat volutpat. Phasellus euismod Vivamus eleifend eleifend massa, eu posuere nunc laoreet sed. Curabitur at ex sem.\n<h6>NOW<\/h6>\nFusce semper quam mattis ultrices posuere. Aliquam eu urna sed lacus convallis porttitor ut vel risus. Donec non metus sed arcu iaculis iaculis quis a arcu. Curabitur tincidunt sollicitudin ligula. Morbi quis nibh nec ipsum laoreet consequat non nec nulla. Phasellus quis molestie mauris. Mauris auctor venenatis ante, eu rhoncus eros pulvinar at. Quisque rhoncus non arcu ut vestibulumCurabitur vel ligula id ipsum molestie consequat. Mauris vel velit ac purus viverra also consequat sed quis diam. Proin elit turpis\n\nalso ligula id ipsum molestie consequat. Mauris vel velit ac purus viverra consequat sed quis diam. Proin elit turpis\n\nullamcorper. Proin id dapibus ante.\n<h6>celerisque<\/h6>\nat massa et, interdum convallis tellus. Fusce at also tortor elementum, mollis ex non, ornare ante. Fusce malesuada,\n\nalso Integer lobortis scelerisque vulputate. Aliquam mollis sed dui et viverra. Aliquam in auctor ante, sed congue erat. Praesent fringilla pharetra imperdiet. Vivamus eleifend eleifend massa, eu posuere nunc laoreet sed. Curabitur at ex sem. Duis varius diam vitae finibus egestas. Fusce auctor pretium ornare. Donec non neque eleifend, finibus erat ac, faucibus massa<a href=\"https:\/\/merscolombia.com\/\">.<\/a><a href=\"https:\/\/rhinoequipment.us\/pt\/\">.<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ask a Question \u00a0 Request a Quote \u00a0 Brochure Download RH3255EX HYDRAULIC HAMMER Previous slide Next slide Efficiency and Profitability MAXIMIZE UPTIME AND INCREASE BOTH EFFICIENCY AND PROFITABILITY The RH3255\u00a0 with a wide range of carrier compatibility, is a breaker for every job, whether you\u2019re doing commercial demolition, road building, quarry work, or production breaking. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6827","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RH3255EX HYDRAULIC HAMMER - Rhino Equipment<\/title>\n<meta name=\"description\" content=\"RH3255EX HYDRAULIC HAMMER Maximize uptime and profitability. Versatile across various carriers for commercial demolition, road building.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rhinoequipment.us\/pt\/rh3255ex-hydraulic-hammer\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/\",\"url\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/\",\"name\":\"RH3255EX HYDRAULIC HAMMER - Rhino Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rhinoequipment.us\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hammerinf3.jpg\",\"datePublished\":\"2022-09-21T18:45:46+00:00\",\"dateModified\":\"2024-12-30T21:20:52+00:00\",\"description\":\"RH3255EX HYDRAULIC HAMMER Maximize uptime and profitability. Versatile across various carriers for commercial demolition, road building.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rhinoequipment.us\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hammerinf3.jpg\",\"contentUrl\":\"https:\\\/\\\/rhinoequipment.us\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/hammerinf3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/rh3255ex-hydraulic-hammer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rhinoequipment.us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RH3255EX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#website\",\"url\":\"https:\\\/\\\/rhinoequipment.us\\\/\",\"name\":\"Rhino Equipment\",\"description\":\"Full Line of Construction Equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#organization\"},\"alternateName\":\"Rhino Equipment\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rhinoequipment.us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#organization\",\"name\":\"Rhino Equipment\",\"url\":\"https:\\\/\\\/rhinoequipment.us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rhinoequipment.us\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rhino_equipment.jpg\",\"contentUrl\":\"https:\\\/\\\/rhinoequipment.us\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Rhino_equipment.jpg\",\"width\":106,\"height\":72,\"caption\":\"Rhino Equipment\"},\"image\":{\"@id\":\"https:\\\/\\\/rhinoequipment.us\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RhinoEqUsa\\\/\",\"https:\\\/\\\/x.com\\\/Rhino_Eq\",\"https:\\\/\\\/www.instagram.com\\\/rhinoeq_usa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/rhinoeq\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RH3255EX HYDRAULIC HAMMER - Rhino Equipment","description":"RH3255EX HYDRAULIC HAMMER Maximize uptime and profitability. Versatile across various carriers for commercial demolition, road building.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rhinoequipment.us\/pt\/rh3255ex-hydraulic-hammer\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/","url":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/","name":"RH3255EX HYDRAULIC HAMMER - Rhino Equipment","isPartOf":{"@id":"https:\/\/rhinoequipment.us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/#primaryimage"},"image":{"@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/#primaryimage"},"thumbnailUrl":"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf3.jpg","datePublished":"2022-09-21T18:45:46+00:00","dateModified":"2024-12-30T21:20:52+00:00","description":"RH3255EX HYDRAULIC HAMMER Maximize uptime and profitability. Versatile across various carriers for commercial demolition, road building.","breadcrumb":{"@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/#primaryimage","url":"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf3.jpg","contentUrl":"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/09\/hammerinf3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/rhinoequipment.us\/rh3255ex-hydraulic-hammer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rhinoequipment.us\/"},{"@type":"ListItem","position":2,"name":"RH3255EX"}]},{"@type":"WebSite","@id":"https:\/\/rhinoequipment.us\/#website","url":"https:\/\/rhinoequipment.us\/","name":"Rhino Equipment","description":"Full Line of Construction Equipment","publisher":{"@id":"https:\/\/rhinoequipment.us\/#organization"},"alternateName":"Rhino Equipment","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rhinoequipment.us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/rhinoequipment.us\/#organization","name":"Rhino Equipment","url":"https:\/\/rhinoequipment.us\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/rhinoequipment.us\/#\/schema\/logo\/image\/","url":"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/06\/Rhino_equipment.jpg","contentUrl":"https:\/\/rhinoequipment.us\/wp-content\/uploads\/2022\/06\/Rhino_equipment.jpg","width":106,"height":72,"caption":"Rhino Equipment"},"image":{"@id":"https:\/\/rhinoequipment.us\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RhinoEqUsa\/","https:\/\/x.com\/Rhino_Eq","https:\/\/www.instagram.com\/rhinoeq_usa\/","https:\/\/www.youtube.com\/user\/rhinoeq"]}]}},"_links":{"self":[{"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/pages\/6827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/comments?post=6827"}],"version-history":[{"count":5,"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/pages\/6827\/revisions"}],"predecessor-version":[{"id":23854,"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/pages\/6827\/revisions\/23854"}],"wp:attachment":[{"href":"https:\/\/rhinoequipment.us\/pt\/wp-json\/wp\/v2\/media?parent=6827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}